{"id":11191,"date":"2024-03-25T14:01:22","date_gmt":"2024-03-25T06:01:22","guid":{"rendered":"https:\/\/chinacncparts.com\/?post_type=product&#038;p=11191"},"modified":"2026-06-02T14:27:17","modified_gmt":"2026-06-02T06:27:17","slug":"maquina-de-corte-por-laser-de-co2-con-camara-ccd","status":"publish","type":"product","link":"https:\/\/www.accteklaser.com\/es\/product\/co2-laser-cutting-machine-with-ccd-camera\/","title":{"rendered":"M\u00e1quina de corte por l\u00e1ser de CO2 con c\u00e1mara CCD"},"content":{"rendered":"<p>La m\u00e1quina de corte l\u00e1ser de CO2 con c\u00e1mara CCD ofrece un corte preciso y automatizado de materiales no met\u00e1licos, combinando posicionamiento visual, salida l\u00e1ser estable y control de movimiento suave.<\/p>","protected":false},"excerpt":{"rendered":"<p>La m\u00e1quina de corte l\u00e1ser de CO2 con c\u00e1mara CCD ofrece un corte preciso y automatizado de materiales no met\u00e1licos, combinando posicionamiento visual, salida l\u00e1ser estable y control de movimiento suave.<\/p>","protected":false},"featured_media":2188,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[104,73],"product_tag":[],"class_list":["post-11191","product","type-product","status-publish","has-post-thumbnail","product_cat-co2-laser-cutting-machine","product_cat-co2-laser-cutting-machine-with-ccd-camera","first","instock","shipping-taxable","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.accteklaser.com\/es\/wp-json\/wp\/v2\/product\/11191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.accteklaser.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.accteklaser.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.accteklaser.com\/es\/wp-json\/wp\/v2\/comments?post=11191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.accteklaser.com\/es\/wp-json\/wp\/v2\/media\/2188"}],"wp:attachment":[{"href":"https:\/\/www.accteklaser.com\/es\/wp-json\/wp\/v2\/media?parent=11191"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.accteklaser.com\/es\/wp-json\/wp\/v2\/product_brand?post=11191"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.accteklaser.com\/es\/wp-json\/wp\/v2\/product_cat?post=11191"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.accteklaser.com\/es\/wp-json\/wp\/v2\/product_tag?post=11191"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}